{"id":25506,"date":"2023-05-30T06:53:25","date_gmt":"2023-05-30T06:53:25","guid":{"rendered":"https:\/\/www.artestar.eu\/al-por-mayor\/perlas-cultivadas-medio-perforados-80-pares\/"},"modified":"2024-10-22T15:51:01","modified_gmt":"2024-10-22T15:51:01","slug":"perle-coltivate-media-perforate-80-paia","status":"publish","type":"product","link":"https:\/\/www.artestar.eu\/it\/vendita-all-ingrosso\/perle-coltivate-media-perforate-80-paia\/","title":{"rendered":"Perle coltivate mediamente perforate 80 paia"},"content":{"rendered":"<p>Perle coltivate mediamente perforate: 5,5 mm.<\/p>\n<ul>\n<li>Le perle coltivate semiforate sono disponibili in diverse dimensioni. Quindi puoi scegliere la taglia o le dimensioni pi\u00f9 adatte a te e fai da te per realizzare qualsiasi stile di orecchini che ti piace.<\/li>\n<li>Le perle coltivate d&#8217;acqua dolce naturali al 100% provengono da ostriche, che hanno una forma rotonda naturale. Tutte le perle naturali d&#8217;acqua dolce sono uniche e hanno una superficie rotonda e liscia, che le rende molto comode da indossare. Se guardi da vicino, vedrai anche la trama superficiale unica delle perle coltivate naturali, che conferisce loro un tocco naturale ed elegante.<\/li>\n<li>Le perle naturali coltivate d&#8217;acqua dolce non sono solo fresche, confortevoli ed eleganti, ma anche versatili. Queste perle semiforate e sciolte sono solitamente adatte per orecchini, puntine e molto altro. Dal momento che abbiamo queste perle in fori semi-alati, non dovrai lottare per perforarle.<\/li>\n<li>Le perle coltivate d&#8217;acqua dolce sono ottimi accessori per l&#8217;artigianato. Possiamo usare questi accessori per gli orecchini per realizzare qualsiasi mestiere creativo che ci piace. Il prodotto finito pu\u00f2 essere regalato ad amici e parenti in occasione di matrimoni, compleanni, anniversari e molte altre occasioni. Siamo sicuri che li ameranno, poich\u00e9 aumenteranno facilmente la fiducia e il fascino di una donna.<\/li>\n<\/ul>\n<h5>Perle coltivate semiperforate<\/h5>\n<ul>\n<li>Tutte le perle coltivate al naturale sono uniche. A causa dell&#8217;illuminazione e delle impostazioni del computer, il prodotto ricevuto pu\u00f2 variare leggermente, leggi le dimensioni delle diverse perle a mezzo diamante prima dell&#8217;acquisto e scegli la carta che ti piace di pi\u00f9.<\/li>\n<li>La madreperla proviene da diversi tipi di molluschi marini, come le ostriche. Se provi ad aprire un guscio di ostrica e guardi da vicino la sua superficie interna, vedrai che \u00e8 leggermente lucido e scintillante. Con esso puoi realizzare bellissimi oggetti decorativi che attireranno molta attenzione.<\/li>\n<li>Si dice che le perle naturali coltivate d&#8217;acqua dolce non siano solo belle, ma siano anche attribuite ai poteri curativi. Possono aiutare a calmare il cuore; sbarazzarsi di fobie sociali o attacchi di panico e depressioni causate da bassi livelli di serotonina; migliorare la memoria attivando la produzione di fattori di crescita nelle cellule nervose nel cervello; e stimolare la produzione di collagene, che rigenera rapidamente lo strato cutaneo del nostro corpo e ci fa sentire belli e vibranti.<\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<ul>\n<li>Dimensioni: ca. \u03a65.5 millimetri<\/li>\n<li>Quantit\u00e0: ca. 80 paia (160 pezzi)<\/li>\n<li>Materiale: perle naturali coltivate d&#8217;acqua dolce<\/li>\n<li>Utilizzato per fare orecchini, bracciali e altri gioielli<\/li>\n<\/ul>\n","protected":false},"featured_media":12049,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_cat":[1519,1520,1495],"product_tag":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v20.5 (Yoast SEO v21.5) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Perle coltivate a media perforazione - Artestar<\/title>\n<meta name=\"description\" content=\"Le perle coltivate d&#039;acqua dolce semiperforate al 100% naturali provengono da ostriche, che hanno una forma rotonda naturale.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.artestar.eu\/it\/vendita-all-ingrosso\/perle-coltivate-media-perforate-80-paia\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Perle coltivate mediamente perforate 80 paia\" \/>\n<meta property=\"og:description\" content=\"Le perle coltivate d&#039;acqua dolce semiperforate al 100% naturali provengono da ostriche, che hanno una forma rotonda naturale.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.artestar.eu\/it\/vendita-all-ingrosso\/perle-coltivate-media-perforate-80-paia\/\" \/>\n<meta property=\"og:site_name\" content=\"Artestar\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/ARTESTAREU\" \/>\n<meta property=\"article:modified_time\" content=\"2024-10-22T15:51:01+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.artestar.eu\/wp-content\/uploads\/2023\/05\/cultured-pearls-accessories-for-earrings-half-perforated-80-pairs.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"600\" \/>\n\t<meta property=\"og:image:height\" content=\"600\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Prezzo\" \/>\n\t<meta name=\"twitter:data1\" content=\"18,31&nbsp;&euro; (IVA non inclusa)\" \/>\n\t<meta name=\"twitter:label2\" content=\"Availability\" \/>\n\t<meta name=\"twitter:data2\" content=\"In stock\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.artestar.eu\/it\/vendita-all-ingrosso\/perle-coltivate-media-perforate-80-paia\/\",\"url\":\"https:\/\/www.artestar.eu\/it\/vendita-all-ingrosso\/perle-coltivate-media-perforate-80-paia\/\",\"name\":\"Perle coltivate a media perforazione - Artestar\",\"isPartOf\":{\"@id\":\"https:\/\/www.artestar.eu\/it\/#website\"},\"datePublished\":\"2023-05-30T06:53:25+00:00\",\"dateModified\":\"2024-10-22T15:51:01+00:00\",\"description\":\"Le perle coltivate d'acqua dolce semiperforate al 100% naturali provengono da ostriche, che hanno una forma rotonda naturale.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.artestar.eu\/it\/vendita-all-ingrosso\/perle-coltivate-media-perforate-80-paia\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.artestar.eu\/it\/vendita-all-ingrosso\/perle-coltivate-media-perforate-80-paia\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.artestar.eu\/it\/vendita-all-ingrosso\/perle-coltivate-media-perforate-80-paia\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Artestar\",\"item\":\"https:\/\/www.artestar.eu\/it\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Vendita all&#8217;ingrosso\",\"item\":\"https:\/\/www.artestar.eu\/it\/vendita-all-ingrosso\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Perle coltivate mediamente perforate 80 paia\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.artestar.eu\/it\/#website\",\"url\":\"https:\/\/www.artestar.eu\/it\/\",\"name\":\"Artestar\",\"description\":\"Mayorista en abalorios y joyer\u00eda\",\"publisher\":{\"@id\":\"https:\/\/www.artestar.eu\/it\/#organization\"},\"alternateName\":\"Artestar-EU\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.artestar.eu\/it\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"it-IT\"},{\"@type\":[\"Organization\",\"Place\"],\"@id\":\"https:\/\/www.artestar.eu\/it\/#organization\",\"name\":\"RUBY ABALORIO S.L.\",\"alternateName\":\"Artestar\",\"url\":\"https:\/\/www.artestar.eu\/it\/\",\"logo\":{\"@id\":\"https:\/\/www.artestar.eu\/it\/vendita-all-ingrosso\/perle-coltivate-media-perforate-80-paia\/#local-main-organization-logo\"},\"image\":{\"@id\":\"https:\/\/www.artestar.eu\/it\/vendita-all-ingrosso\/perle-coltivate-media-perforate-80-paia\/#local-main-organization-logo\"},\"sameAs\":[\"https:\/\/www.facebook.com\/ARTESTAREU\",\"https:\/\/www.instagram.com\/artestareu\/\",\"https:\/\/www.pinterest.es\/artestar_eu\/\",\"https:\/\/www.tiktok.com\/@artestar_wholesale\"],\"openingHoursSpecification\":[{\"@type\":\"OpeningHoursSpecification\",\"dayOfWeek\":[\"Monday\",\"Tuesday\",\"Wednesday\",\"Thursday\",\"Friday\",\"Saturday\",\"Sunday\"],\"opens\":\"09:00\",\"closes\":\"17:00\"}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/www.artestar.eu\/it\/vendita-all-ingrosso\/perle-coltivate-media-perforate-80-paia\/#local-main-organization-logo\",\"url\":\"https:\/\/www.artestar.eu\/wp-content\/uploads\/2023\/05\/cropped-png.png\",\"contentUrl\":\"https:\/\/www.artestar.eu\/wp-content\/uploads\/2023\/05\/cropped-png.png\",\"width\":512,\"height\":512,\"caption\":\"RUBY ABALORIO S.L.\"}]}<\/script>\n<meta property=\"product:price:amount\" content=\"18.31\" \/>\n<meta property=\"product:price:currency\" content=\"EUR\" \/>\n<meta property=\"og:availability\" content=\"instock\" \/>\n<meta property=\"product:availability\" content=\"instock\" \/>\n<meta property=\"product:retailer_item_id\" content=\"ZZ-ES-0006\" \/>\n<meta property=\"product:condition\" content=\"new\" \/>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Perle coltivate a media perforazione - Artestar","description":"Le perle coltivate d'acqua dolce semiperforate al 100% naturali provengono da ostriche, che hanno una forma rotonda naturale.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.artestar.eu\/it\/vendita-all-ingrosso\/perle-coltivate-media-perforate-80-paia\/","og_locale":"it_IT","og_type":"article","og_title":"Perle coltivate mediamente perforate 80 paia","og_description":"Le perle coltivate d'acqua dolce semiperforate al 100% naturali provengono da ostriche, che hanno una forma rotonda naturale.","og_url":"https:\/\/www.artestar.eu\/it\/vendita-all-ingrosso\/perle-coltivate-media-perforate-80-paia\/","og_site_name":"Artestar","article_publisher":"https:\/\/www.facebook.com\/ARTESTAREU","article_modified_time":"2024-10-22T15:51:01+00:00","og_image":[{"width":600,"height":600,"url":"https:\/\/www.artestar.eu\/wp-content\/uploads\/2023\/05\/cultured-pearls-accessories-for-earrings-half-perforated-80-pairs.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Prezzo":"18,31&nbsp;&euro; (IVA non inclusa)","Availability":"In stock"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.artestar.eu\/it\/vendita-all-ingrosso\/perle-coltivate-media-perforate-80-paia\/","url":"https:\/\/www.artestar.eu\/it\/vendita-all-ingrosso\/perle-coltivate-media-perforate-80-paia\/","name":"Perle coltivate a media perforazione - Artestar","isPartOf":{"@id":"https:\/\/www.artestar.eu\/it\/#website"},"datePublished":"2023-05-30T06:53:25+00:00","dateModified":"2024-10-22T15:51:01+00:00","description":"Le perle coltivate d'acqua dolce semiperforate al 100% naturali provengono da ostriche, che hanno una forma rotonda naturale.","breadcrumb":{"@id":"https:\/\/www.artestar.eu\/it\/vendita-all-ingrosso\/perle-coltivate-media-perforate-80-paia\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.artestar.eu\/it\/vendita-all-ingrosso\/perle-coltivate-media-perforate-80-paia\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.artestar.eu\/it\/vendita-all-ingrosso\/perle-coltivate-media-perforate-80-paia\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Artestar","item":"https:\/\/www.artestar.eu\/it\/"},{"@type":"ListItem","position":2,"name":"Vendita all&#8217;ingrosso","item":"https:\/\/www.artestar.eu\/it\/vendita-all-ingrosso\/"},{"@type":"ListItem","position":3,"name":"Perle coltivate mediamente perforate 80 paia"}]},{"@type":"WebSite","@id":"https:\/\/www.artestar.eu\/it\/#website","url":"https:\/\/www.artestar.eu\/it\/","name":"Artestar","description":"Mayorista en abalorios y joyer\u00eda","publisher":{"@id":"https:\/\/www.artestar.eu\/it\/#organization"},"alternateName":"Artestar-EU","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.artestar.eu\/it\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"it-IT"},{"@type":["Organization","Place"],"@id":"https:\/\/www.artestar.eu\/it\/#organization","name":"RUBY ABALORIO S.L.","alternateName":"Artestar","url":"https:\/\/www.artestar.eu\/it\/","logo":{"@id":"https:\/\/www.artestar.eu\/it\/vendita-all-ingrosso\/perle-coltivate-media-perforate-80-paia\/#local-main-organization-logo"},"image":{"@id":"https:\/\/www.artestar.eu\/it\/vendita-all-ingrosso\/perle-coltivate-media-perforate-80-paia\/#local-main-organization-logo"},"sameAs":["https:\/\/www.facebook.com\/ARTESTAREU","https:\/\/www.instagram.com\/artestareu\/","https:\/\/www.pinterest.es\/artestar_eu\/","https:\/\/www.tiktok.com\/@artestar_wholesale"],"openingHoursSpecification":[{"@type":"OpeningHoursSpecification","dayOfWeek":["Monday","Tuesday","Wednesday","Thursday","Friday","Saturday","Sunday"],"opens":"09:00","closes":"17:00"}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.artestar.eu\/it\/vendita-all-ingrosso\/perle-coltivate-media-perforate-80-paia\/#local-main-organization-logo","url":"https:\/\/www.artestar.eu\/wp-content\/uploads\/2023\/05\/cropped-png.png","contentUrl":"https:\/\/www.artestar.eu\/wp-content\/uploads\/2023\/05\/cropped-png.png","width":512,"height":512,"caption":"RUBY ABALORIO S.L."}]},"product_price_amount":"18.31","product_price_currency":"EUR","og_availability":"instock","product_availability":"instock","product_retailer_item_id":"ZZ-ES-0006","product_condition":"new"},"tiered_pricing_type":"fixed","tiered_pricing_fixed_rules":[],"tiered_pricing_percentage_rules":[],"tiered_pricing_minimum":null,"_administrator_tiered_pricing_type":"fixed","_administrator_tiered_pricing_fixed_rules":[],"_editor_tiered_pricing_type":"fixed","_editor_tiered_pricing_fixed_rules":[],"_author_tiered_pricing_type":"fixed","_author_tiered_pricing_fixed_rules":[],"_contributor_tiered_pricing_type":"fixed","_contributor_tiered_pricing_fixed_rules":[],"_subscriber_tiered_pricing_type":"fixed","_subscriber_tiered_pricing_fixed_rules":[],"_wpseo_manager_tiered_pricing_type":"fixed","_wpseo_manager_tiered_pricing_fixed_rules":[],"_wpseo_editor_tiered_pricing_type":"fixed","_wpseo_editor_tiered_pricing_fixed_rules":[],"_customer_tiered_pricing_type":"fixed","_customer_tiered_pricing_fixed_rules":[],"_shop_manager_tiered_pricing_type":"fixed","_shop_manager_tiered_pricing_fixed_rules":[],"_product_manager_tiered_pricing_type":"fixed","_product_manager_tiered_pricing_fixed_rules":[],"_links":{"self":[{"href":"https:\/\/www.artestar.eu\/it\/wp-json\/wp\/v2\/product\/25506"}],"collection":[{"href":"https:\/\/www.artestar.eu\/it\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.artestar.eu\/it\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/www.artestar.eu\/it\/wp-json\/wp\/v2\/comments?post=25506"}],"version-history":[{"count":2,"href":"https:\/\/www.artestar.eu\/it\/wp-json\/wp\/v2\/product\/25506\/revisions"}],"predecessor-version":[{"id":37256,"href":"https:\/\/www.artestar.eu\/it\/wp-json\/wp\/v2\/product\/25506\/revisions\/37256"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.artestar.eu\/it\/wp-json\/wp\/v2\/media\/12049"}],"wp:attachment":[{"href":"https:\/\/www.artestar.eu\/it\/wp-json\/wp\/v2\/media?parent=25506"}],"wp:term":[{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.artestar.eu\/it\/wp-json\/wp\/v2\/product_cat?post=25506"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.artestar.eu\/it\/wp-json\/wp\/v2\/product_tag?post=25506"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}